{"id":69010,"date":"2022-03-31T10:00:50","date_gmt":"2022-03-31T08:00:50","guid":{"rendered":"https:\/\/www.fotocasa.es\/fotocasa-life\/?p=69010"},"modified":"2022-03-07T11:43:23","modified_gmt":"2022-03-07T10:43:23","slug":"mesdelamujer-angeles-albanila-yo-era-cocinera-y-cambie-radicalmente-y-ya-no-cambio-el-poder-estar-al-aire-libre-todos-los-dias","status":"publish","type":"post","link":"https:\/\/www.fotocasa.es\/fotocasa-life\/construccion\/mesdelamujer-angeles-albanila-yo-era-cocinera-y-cambie-radicalmente-y-ya-no-cambio-el-poder-estar-al-aire-libre-todos-los-dias\/","title":{"rendered":"#MesDeLaMujer \u00c1ngeles, alba\u00f1ila, \u201cYo era cocinera y cambi\u00e9 radicalmente y ya no cambio el poder estar al aire libre todos los d\u00edas\u201d"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Con motivo del D\u00eda Internacional de la Mujer, desde <a href=\"https:\/\/www.fotocasa.es\/es\/\"><strong>Fotocasa<\/strong> <\/a>queremos dar una especial visibilidad a todas aquellas mujeres que trabajan en todo lo relacionado con el sector de la construcci\u00f3n.\u00a0 Actualmente algo m\u00e1s de 100.000 mujeres trabajan en el sector de la construcci\u00f3n, lo que<strong> supone el 9,6% de la ocupaci\u00f3n actual del sector,<\/strong> de acuerdo con la Fundaci\u00f3n Laboral de la Construcci\u00f3n. <strong>Hoy entrevistamos a \u00c1ngeles, alba\u00f1ila y fontanera, con m\u00e1s de 7 a\u00f1os de experiencia<\/strong>, para que nos cuente su experiencia en su trabajo.<\/span><\/p>\n<h2>Entrevista a \u00c1ngeles, alba\u00f1ila y fontanera<\/h2>\n<h3><b>\u00bfC\u00f3mo decidiste comenzar a trabajar en este sector?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Pues es algo que siempre me ha llamado la atenci\u00f3n. <strong>Yo ya ten\u00eda conocimientos de fontaner\u00eda por ver a mi padre y a mi hermano que trabajan en este sector<\/strong> y yo observando siempre lo que hac\u00edan, c\u00f3mo pintaban, qu\u00e9 trazos daban, preguntando las dudas. Me llam\u00f3 la atenci\u00f3n y me dije \u201cPues voy a probar\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Y me ha salido bien.<\/span><\/p>\n<h3><b>\u00bfQu\u00e9 es lo que m\u00e1s te atrajo de este sector?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\"><strong>De la construcci\u00f3n me gusta todo, desde levantar paredes hasta hacer zanjas.<\/strong> Aunque lo que m\u00e1s me gusta es la posibilidad de trabajar casi siempre al aire libre, que no tengas que estar 8 horas en una cocina o en una oficina, quiero evitar en la medida de lo posible estar dentro de un recinto. <strong>Trabajas con compa\u00f1eros que, por suerte, a mi me han tocado muy buenos<\/strong> compa\u00f1eros. Yo me llevo muy bien con ellos, algo que es muy importante al trabajar. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre todas las entrevistas en el Mes de la Mujer Fotocasa<\/p>\n","protected":false},"author":197,"featured_media":69011,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"categories":[4278],"tags":[5352,2298,5339,4578,5340],"class_list":["post-69010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","tag-albanila","tag-construccion","tag-dia-de-la-mujer","tag-entrevistas","tag-mes-de-la-mujer"],"modified_by":"Agustina Battioli","_links":{"self":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/69010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/comments?post=69010"}],"version-history":[{"count":0,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/69010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media\/69011"}],"wp:attachment":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media?parent=69010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/categories?post=69010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/tags?post=69010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}