{"id":44504,"date":"2020-01-14T10:09:00","date_gmt":"2020-01-14T08:09:00","guid":{"rendered":"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/?p=44504"},"modified":"2020-11-27T13:11:57","modified_gmt":"2020-11-27T12:11:57","slug":"trucos-para-ahorrar-en-la-cuesta-de-enero","status":"publish","type":"post","link":"https:\/\/www.fotocasa.es\/fotocasa-life\/hogar\/trucos-para-ahorrar-en-la-cuesta-de-enero\/","title":{"rendered":"Trucos para ahorrar en la cuesta de enero"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La Navidad ya ha pasado, y con ella, seguramente un mont\u00f3n de gastos imprevistos. La cuesta de enero existe, pero tambi\u00e9n hay muchos trucos de ahorro para intentar pasarla lo mejor posible. <\/span><b>Los suministros de un hogar<\/b><span style=\"font-weight: 400;\">, por ejemplo, <\/span><b>se llevan gran porcentaje de nuestro sueldo, sobre todo en los meses fr\u00edos. \u00bfNo ser\u00eda interesante controlarlos un poco?<\/b><span style=\"font-weight: 400;\"> habitissimo te propone varios trucos para que la cuesta de enero sea m\u00e1s llevadera.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44003\" src=\"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/wp-content\/uploads\/2019\/12\/calefaccion.jpg\" alt=\"- - - -\" width=\"980\" height=\"550\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/12\/calefaccion.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/12\/calefaccion-300x168.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/12\/calefaccion-150x84.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/12\/calefaccion-768x431.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<h2>Controlar la temperatura del hogar<\/h2>\n<p><span style=\"font-weight: 400;\">La <\/span><b>calefacci\u00f3n en invierno <\/b><span style=\"font-weight: 400;\">puede hacer verdaderos estragos en nuestra factura de suministros. Por cada grado que subamos la temperatura, el consumo aumentar\u00e1 en torno a un 7%. Teniendo en cuenta esto, hay que a\u00f1adir que<\/span><b> la temperatura adecuada de una estancia est\u00e1 entre 19 y 21\u00ba<\/b><span style=\"font-weight: 400;\">. Ahora bien, en los dormitorios esta temperatura puede descender perfectamente hasta los 16\u00ba.<\/span><\/p>\n<p><b>No dejes la calefacci\u00f3n encendida cuando duermas<\/b><span style=\"font-weight: 400;\">, es mejor dejarla durante la tarde y luego dormir con el calor residual. Adem\u00e1s, por la ma\u00f1ana, no la enciendas hasta ventilar la casa correctamente y cerrarlo todo bien. Por \u00faltimo, no cubras jam\u00e1s los radiadores ni pongas obst\u00e1culos. La distribuci\u00f3n del calor ser\u00e1 mejor. Y cierra tambi\u00e9n esos radiadores que est\u00e1n en habitaciones que no se usan, es un gasto innecesario.<\/span><\/p>\n<h2>Mejorar el aislamiento de la vivienda<\/h2>\n<p><span style=\"font-weight: 400;\">Aunque controlar la temperatura en casa puede ser una de las mejores opciones a la hora de ahorrar, no podemos dejar de lado el tema del aislamiento. Por mucho que nos controlemos nosotros,<\/span><b> si la casa est\u00e1 mal aislada, el calor se escapar\u00e1 dejando entrar fr\u00edo y haci\u00e9ndonos gastar el doble.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Mejora el aislamiento de tu casa mediante burletes en la puerta y ventanas. Recuerda, adem\u00e1s, que por las ventanas es por donde hay m\u00e1s p\u00e9rdida de calor. El <\/span><b>sistema de doble cristal o doble ventana<\/b><span style=\"font-weight: 400;\"> reduce much\u00edsimo estas p\u00e9rdidas, la condensaci\u00f3n de agua y la formaci\u00f3n de escarcha. Quiz\u00e1 no ser\u00eda mala idea pensar en un cambio de ventanas para 2020, \u00bfverdad?<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32758\" src=\"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/wp-content\/uploads\/2018\/10\/electrodom\u00e9sticos.jpg\" alt=\"Cinco v\u00edas para financiar la compra de grandes electrodom\u00e9sticos\" width=\"980\" height=\"550\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/10\/electrodom\u00e9sticos.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/10\/electrodom\u00e9sticos-300x168.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/10\/electrodom\u00e9sticos-150x84.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/10\/electrodom\u00e9sticos-768x431.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<h2>La importancia de los electrodom\u00e9sticos<\/h2>\n<p><span style=\"font-weight: 400;\">En la<\/span><b> factura de la luz<\/b><span style=\"font-weight: 400;\">, tambi\u00e9n se refleja el gasto de nuestros electrodom\u00e9sticos. S\u00ed, seguramente la luz de tu comedor no estar\u00e1 siempre encendida, pero el frigor\u00edfico s\u00ed. Por este motivo, para mayor ahorro, es imprescindible contar con <\/span><b>electrodom\u00e9sticos de clase A, que consumen un 70% menos<\/b><span style=\"font-weight: 400;\"> de energ\u00eda que uno de clase G.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si nos fijamos en el frigor\u00edfico, nos daremos cuenta de que siempre est\u00e1 trabajando. Un buen consejo es no comprar un frigor\u00edfico m\u00e1s grande del que necesitamos. <strong>As\u00ed evitaremos mayor consumo<\/strong>. En el caso de la lavadora o el lavavajillas, aunque su uso no es continuo, pueden llegar a gastar bastante, tanto agua como luz. El mejor consejo es intentar que al ponerlo est\u00e9 siempre lleno, nada de medias cargas.<\/span><\/p>\n<h2>Ahorra agua<\/h2>\n<p><span style=\"font-weight: 400;\">Aunque el gasto de agua suele ser inferior al resto de suministros, no est\u00e1 de m\u00e1s controlarlo. M\u00e1s a\u00fan sabiendo los problemas de sequ\u00eda que tenemos en este pa\u00eds. Racionaliza el consumo y no dejes los grifos abiertos durante tareas rutinarias como el cepillado de dientes o el afeitado. Adem\u00e1s, tambi\u00e9n te ayudar\u00e1 colocar<\/span><b> reguladores de temperatura como el termostato<\/b><span style=\"font-weight: 400;\"> para ahorrar entre un 4 y un 6% de energ\u00eda. Como dato, recuerda que la temperatura del agua para el aseo personal debe estar entre los 30 y 35\u00ba.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestras finanzas est\u00e1n resentidas por la Navidad y ahora toca reponerse. habitissimo te da los mejores trucos para ahorrar en la cuesta de enero.<\/p>\n","protected":false},"author":24,"featured_media":44507,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"categories":[2285],"tags":[2421,15,2288,2369],"class_list":["post-44504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar","tag-ahorrar","tag-ahorro","tag-ahorro-energetico","tag-trucos-para-ahorrar"],"modified_by":"fotocasa","_links":{"self":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/44504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/comments?post=44504"}],"version-history":[{"count":0,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/44504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media\/44507"}],"wp:attachment":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media?parent=44504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/categories?post=44504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/tags?post=44504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}