{"id":40762,"date":"2019-09-10T08:00:08","date_gmt":"2019-09-10T06:00:08","guid":{"rendered":"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/?p=40762"},"modified":"2020-11-27T13:16:21","modified_gmt":"2020-11-27T12:16:21","slug":"10-propositos-para-renovar-tu-casa-y-tu-espiritu-en-septiembre","status":"publish","type":"post","link":"https:\/\/www.fotocasa.es\/fotocasa-life\/hogar\/10-propositos-para-renovar-tu-casa-y-tu-espiritu-en-septiembre\/","title":{"rendered":"10 prop\u00f3sitos para renovar tu casa (y tu esp\u00edritu) en septiembre"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Septiembre es como enero:<\/span><b> el mes de los buenos prop\u00f3sitos<\/b><span style=\"font-weight: 400;\"> e intenciones tras el par\u00f3n de las vacaciones de verano. \u00bfQue nos hemos sobrepasado con las comidas? Pues toca<\/span><b> empezar dieta <\/b><span style=\"font-weight: 400;\">y <\/span><b>el gimnasio<\/b><span style=\"font-weight: 400;\">. \u00bfQue queremos renovarnos espiritualmente? Pues nos apuntamos a <\/span><b>yoga<\/b><span style=\"font-weight: 400;\">. \u00bfQue nos ha fascinado otra cultura? Pues compramos libros para indagar m\u00e1s sobre su historia. Y as\u00ed,<\/span><b> una larga lista de <\/b><b><i>to-do\u2019s<\/i><\/b><span style=\"font-weight: 400;\"> que acaba con la <\/span><b>redecoraci\u00f3n del hogar<\/b><span style=\"font-weight: 400;\">. Que tanta energ\u00eda hay que canalizarla de alg\u00fan modo\u2026 \u00a1Te sugerimos 10 prop\u00f3sitos para<\/span><b> renovar tu casa y tu esp\u00edritu<\/b><span style=\"font-weight: 400;\"> en septiembre!<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40765\" src=\"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/wp-content\/uploads\/2019\/09\/calendario.jpg\" alt=\"- - - -\" width=\"980\" height=\"550\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/calendario.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/calendario-300x168.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/calendario-150x84.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/calendario-768x431.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<h2>Tener un calendario para organizarlo todo<\/h2>\n<p><span style=\"font-weight: 400;\">Septiembre es sin\u00f3nimo de la <\/span><b>vuelta al cole, al trabajo, a los tr\u00e1mites burocr\u00e1ticos<\/b><span style=\"font-weight: 400;\"> y gestiones de todo tipo\u2026 Claramente, <\/span><b>necesitas un calendario<\/b><span style=\"font-weight: 400;\"> para que no se te olvide nada. Un calendario grande, que puedas <\/span><b>colgar en la pared <\/b><span style=\"font-weight: 400;\">y garabatear lo que haga falta, pero que, al mismo tiempo, decore.\u00a0<\/span><\/p>\n<h2>Llevar un estilo de vida m\u00e1s sostenible<\/h2>\n<p><span style=\"font-weight: 400;\">Imaginamos que muchos hab\u00e9is viajado a aut\u00e9nticos <\/span><b>para\u00edsos naturales <\/b><span style=\"font-weight: 400;\">y eso os ha hecho reflexionar sobre la importancia de <\/span><b>ser m\u00e1s respetuosos con el medio ambiente<\/b><span style=\"font-weight: 400;\">. As\u00ed que te has propuesto <\/span><b>aparcar el coche e ir en bici <\/b><span style=\"font-weight: 400;\">al trabajo, \u00a1enhorabuena! Ahora solo necesitas un <\/span><b>sistema para guardar la bici en casa<\/b><span style=\"font-weight: 400;\"> que sea \u00fatil y, adem\u00e1s, decore. \u00bfQu\u00e9 te parecen estas opciones?<\/span><\/p>\n<h2>Regalarse peque\u00f1os placeres<\/h2>\n<p><span style=\"font-weight: 400;\">Si te has pasado medio verano balance\u00e1ndote en una <\/span><b>hamaca <\/b><span style=\"font-weight: 400;\">y te ha parecido un verdadero placer, \u00bfpor qu\u00e9 no poner una en tu casa, que puedas disfrutar durante todo el a\u00f1o? Cada vez m\u00e1s hogares se atreven a<\/span><b> incluir una <\/b><b>hamaca o una silla colgante en su decoraci\u00f3n interior.<\/b><span style=\"font-weight: 400;\"> Proporcionan un nuevo<\/span><b> espacio de relax <\/b><span style=\"font-weight: 400;\">y un <\/span><b>elemento decorativo<\/b><span style=\"font-weight: 400;\"> m\u00e1s que original. Lo \u00fanico que se debe tener en cuenta es que el sistema de anclaje sea seguro y resistente. Y t\u00fa, \u00bfte atreves?<\/span><\/p>\n<h2>Empezar el gimnasio, aunque sea en casa<\/h2>\n<p><span style=\"font-weight: 400;\">La <\/span><b>falta de tiempo<\/b><span style=\"font-weight: 400;\"> es la principal excusa para no ir al <\/span><b>gimnasio<\/b><span style=\"font-weight: 400;\">. Pero si te lo montas en casa, ya no tendr\u00e1s motivos para escaquearte de este nuevo prop\u00f3sito de septiembre. Las opciones son amplias: desde reservar<\/span><b> un rinc\u00f3n del sal\u00f3n<\/b><span style=\"font-weight: 400;\"> para poner una bicicleta est\u00e1tica y una esterilla, a <\/span><b>dedicarle una habitaci\u00f3n de la casa<\/b><span style=\"font-weight: 400;\"> entera. Eso ya depender\u00e1 de tus posibilidades, pero si tienes la buhardilla desaprovechada o una habitaci\u00f3n como trastero, plant\u00e9ate dedicar esos espacios a <\/span><b>montar tu propio gimnasio en casa.<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40766\" src=\"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/wp-content\/uploads\/2019\/09\/comer-sano.jpg\" alt=\"- - - -\" width=\"980\" height=\"550\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/comer-sano.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/comer-sano-300x168.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/comer-sano-150x84.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/comer-sano-768x431.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<h2>Comer m\u00e1s sano<\/h2>\n<p><span style=\"font-weight: 400;\">Es absurdo intentar llevar <\/span><b>un estilo de vida m\u00e1s saludable<\/b><span style=\"font-weight: 400;\"> sin cuidar tu alimentaci\u00f3n, \u00bfno crees? Deporte y nutrici\u00f3n van de la mano. Por eso, proponte hacer realidad ese <\/span><b>huerto urbano <\/b><span style=\"font-weight: 400;\">que siempre has querido tener en casa. No hace falta empezar por un gran cultivo, <\/span><b>prueba primero con hierbas arom\u00e1ticas <\/b><span style=\"font-weight: 400;\">y alguna hortaliza, y a medida que te vayas aficionando, incrementa tu producci\u00f3n. Comprobar\u00e1s <\/span><b>lo satisfactorio que es comer sano<\/b><span style=\"font-weight: 400;\"> y de tu propio huerto.<\/span><\/p>\n<h2>Leer m\u00e1s<\/h2>\n<p><span style=\"font-weight: 400;\">En verano se dispara la venta de libros. Eso es porque <\/span><b>durante las vacaciones<\/b><span style=\"font-weight: 400;\"> tenemos suficiente tiempo libre como para <\/span><b>disfrutar m\u00e1s y mejor de la lectura<\/b><span style=\"font-weight: 400;\">, ya sea en la playa o en la terraza de casa. Leer es un h\u00e1bito saludable para la mente y el esp\u00edritu que no deber\u00edamos abandonar cuando volvemos al estr\u00e9s de la rutina. Por eso, an\u00edmate a montar <\/span><b>un bonito rinc\u00f3n de lectura en tu casa<\/b><span style=\"font-weight: 400;\">, te motivar\u00e1 a seguir leyendo fervorosamente todo el a\u00f1o.<\/span><\/p>\n<h2>Volver a estudiar<\/h2>\n<p><span style=\"font-weight: 400;\">\u00bfTe has dado cuenta de que<\/span><b> tu ingl\u00e9s est\u00e1 oxidado<\/b><span style=\"font-weight: 400;\">? \u00bfCrees que ha llegado el momento de <\/span><b>estudiar eso que siempre te gust\u00f3<\/b><span style=\"font-weight: 400;\">, pero que nunca hiciste porque no ten\u00eda salida laboral? Pues enhorabuena, porque septiembre es el mes id\u00f3neo para empezar todo tipo de <\/span><b>cursos acad\u00e9micos<\/b><span style=\"font-weight: 400;\">. Recupera la ilusi\u00f3n por tener <\/span><b>tu propio escritorio y zona de trabajo<\/b><span style=\"font-weight: 400;\">. \u00a1Te sentir\u00e1s como un universitario\/a!<\/span><\/p>\n<h2>Poner tu terraza en condiciones<\/h2>\n<p><span style=\"font-weight: 400;\">Nunca es tarde para <\/span><b>poner tu terraza en condiciones<\/b><span style=\"font-weight: 400;\">, que a\u00fan quedan por disfrutar muchos d\u00edas de sol a lo largo del oto\u00f1o. As\u00ed que, si no te pusiste las pilas en primavera y se te han pasado los meses volando, <\/span><b>septiembre te da una nueva oportunidad<\/b><span style=\"font-weight: 400;\">. \u00a1No le falles!<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40767\" src=\"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/wp-content\/uploads\/2019\/09\/tranquilidad.jpg\" alt=\"- - - -\" width=\"980\" height=\"550\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/tranquilidad.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/tranquilidad-300x168.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/tranquilidad-150x84.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2019\/09\/tranquilidad-768x431.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<h2>Librarse de todas las cosas innecesarias<\/h2>\n<p><span style=\"font-weight: 400;\">Algunos destinos vacacionales pueden hacerte<\/span><b> cuestionar tu forma de ver la vida<\/b><span style=\"font-weight: 400;\">. Y no hace falta irse a visitar una tribu ind\u00edgena, te puede suceder en cualquier pueblo de Espa\u00f1a donde su gente a\u00fan conserva valores, como <\/span><b>la sencillez y el vivir con lo justo y necesario<\/b><span style=\"font-weight: 400;\">. Esto, traducido a un nuevo prop\u00f3sito, significa que hagas limpieza de lo material en casa y<\/span><b> te deshagas de todo aquello que realmente ni usas ni necesitas<\/b><span style=\"font-weight: 400;\">. D\u00f3nalo, reg\u00e1lalo o rec\u00edclalo y opta por<\/span><b> una decoraci\u00f3n m\u00e1s minimalista<\/b><span style=\"font-weight: 400;\">, que no sature la energ\u00eda de tu casa.<\/span><\/p>\n<h2>Esc\u00fachate y act\u00faa<\/h2>\n<p><span style=\"font-weight: 400;\">Seguro que llevas a\u00f1os odiando <\/span><b>el suelo de tu casa<\/b><span style=\"font-weight: 400;\">, <\/span><b>los muebles de la cocina<\/b><span style=\"font-weight: 400;\"> o <\/span><b>los azulejos del ba\u00f1o<\/b><span style=\"font-weight: 400;\">, pero no haces nada y te pones <\/span><b>excusas <\/b><span style=\"font-weight: 400;\">tipo: ahora no puedo gastar, no tengo tiempo, mejor el a\u00f1o que viene, es un piso de alquiler\u2026 y as\u00ed, un largo etc\u00e9tera. Deja de lamentarte y act\u00faa; en<\/span><b> habitissimo<\/b><span style=\"font-weight: 400;\"> te hemos demostrado cientos de veces que <\/span><b>se pueden lograr grandes cambios por muy poco dinero<\/b><span style=\"font-weight: 400;\">. Desde la <\/span><b>obra seca <\/b><span style=\"font-weight: 400;\">a los revestimientos baratos o de<\/span><b> imitaci\u00f3n de materiales<\/b><span style=\"font-weight: 400;\">, pasando por todo lo que <\/span><b>puedes hacer t\u00fa mismo<\/b><span style=\"font-weight: 400;\"> con bricolaje casero. An\u00edmate, \u00a1ver\u00e1s que satisfecho\/a te quedas!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Septiembre es como enero: el mes de los buenos prop\u00f3sitos e intenciones tras el par\u00f3n de las vacaciones de verano. Te damos diez consejos pr\u00e1cticos.<\/p>\n","protected":false},"author":24,"featured_media":40764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"categories":[2285],"tags":[2521,3114],"class_list":["post-40762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar","tag-propositos-verano","tag-septiembre"],"modified_by":"fotocasa","_links":{"self":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/40762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/comments?post=40762"}],"version-history":[{"count":0,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/40762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media\/40764"}],"wp:attachment":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media?parent=40762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/categories?post=40762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/tags?post=40762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}