{"id":40128,"date":"2019-08-19T22:45:39","date_gmt":"2019-08-19T20:45:39","guid":{"rendered":"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/?p=40128"},"modified":"2020-12-16T13:02:05","modified_gmt":"2020-12-16T12:02:05","slug":"los-espanoles-gastaran-160-euros-en-llenar-la-nevera-tras-las-vacaciones","status":"publish","type":"post","link":"https:\/\/www.fotocasa.es\/fotocasa-life\/hogar\/los-espanoles-gastaran-160-euros-en-llenar-la-nevera-tras-las-vacaciones\/","title":{"rendered":"Los espa\u00f1oles gastar\u00e1n 160 euros en llenar la nevera tras las vacaciones"},"content":{"rendered":"<p>Los espa\u00f1oles gastar\u00e1n <strong>alrededor de 160 euros en llenar su nevera tras la vuelta de las vacaciones<\/strong> con productos de alimentaci\u00f3n como carne, fruta y verduras, seg\u00fan el estudio realizado por Tiendeo.com, compa\u00f1\u00eda dedicada a servicios &#8216;drive-to-store&#8217; para el sector &#8216;retail&#8217;.<\/p>\n<p>En concreto, la encuesta se\u00f1ala que ser\u00e1n los <strong>consumidores de entre 55 y 65 a\u00f1os los que m\u00e1s inviertan<\/strong> en llenar la nevera, declarando una media de 175 euros de gasto tras su vuelta a casa.<\/p>\n<p>El informe se\u00f1ala que los supermercados e hipermercados son los favoritos por los consumidores para realizar sus compras. As\u00ed, se prev\u00e9 que el \u00faltimo s\u00e1bado de agosto, el d\u00eda 31, <strong>ser\u00e1 el que mayor tr\u00e1fico de consumidores registre con un incremento del 13% en las visitas a supermercados<\/strong>, coincidiendo con el retorno de muchas familias a sus hogares tras las vacaciones, seg\u00fan los datos obtenidos con Geotracking de Tiendeo.<\/p>\n<p>Respecto a lo que los espa\u00f1oles comprar\u00e1n en su vuelta de vacaciones para llenar la nevera, destacan <strong>la carne, fruta y verduras<\/strong> como los productos en los que se invertir\u00e1 mayor parte del presupuesto, pues as\u00ed lo han declarado seis de cada 10 usuarios de la plataforma, seguidos por el pescado y los productos l\u00e1cteos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los espa\u00f1oles gastar\u00e1n alrededor de 160 euros en llenar su nevera tras las vacaciones con productos de alimentaci\u00f3n como carne, fruta y verduras.<\/p>\n","protected":false},"author":78,"featured_media":40129,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"categories":[2285],"tags":[433,493],"class_list":["post-40128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar","tag-compradores","tag-vacaciones"],"modified_by":"Agustina Battioli","_links":{"self":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/40128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/comments?post=40128"}],"version-history":[{"count":0,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/40128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media\/40129"}],"wp:attachment":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media?parent=40128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/categories?post=40128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/tags?post=40128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}