{"id":39644,"date":"2019-08-01T08:00:15","date_gmt":"2019-08-01T07:00:15","guid":{"rendered":"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/?p=39644"},"modified":"2020-11-27T13:17:21","modified_gmt":"2020-11-27T12:17:21","slug":"ocho-coberturas-de-tu-seguro-de-hogar-que-te-protegen-cuando-no-estas-en-casa","status":"publish","type":"post","link":"https:\/\/www.fotocasa.es\/fotocasa-life\/hogar\/ocho-coberturas-de-tu-seguro-de-hogar-que-te-protegen-cuando-no-estas-en-casa\/","title":{"rendered":"Ocho coberturas de tu seguro de hogar que te protegen cuando no est\u00e1s en casa"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Cuando contratas un <\/span><a href=\"https:\/\/www.kelisto.es\/seguros-hogar\/comparador?utm_source=google&amp;utm_medium=contenidos&amp;utm_campaign=fotocasa\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">seguro de hogar<\/span><\/a><span style=\"font-weight: 400;\"> puede que lo que est\u00e9s pensando sea en proteger tu continente y, c\u00f3mo no, tu contenido de <strong>posibles incidentes o siniestros<\/strong> que puedan ocurrir cuando no est\u00e9s en casa. Te olvidas de las llaves, tu mascota ha decidido que el sof\u00e1 es su peor enemigo\u2026 Para estas y otras situaciones podr\u00e1s contar con una cobertura que, sin duda, te puede sorprender.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La pr\u00e1ctica totalidad de las\u00a0compa\u00f1\u00edas ofrecen, incluso en sus <\/span><a href=\"https:\/\/www.kelisto.es\/seguros-hogar\/mejor-compra\/los-10-seguros-de-hogar-mas-baratos-4453?utm_source=google&amp;utm_medium=contenidos&amp;utm_campaign=fotocasa\" target=\"_blank\" rel=\"noopener noreferrer\"><b>seguros de hogar m\u00e1s baratos<\/b><\/a><span style=\"font-weight: 400;\">, <strong>protecci\u00f3n ante los atracos que se producen fuera del domicilio<\/strong> o la reposici\u00f3n de cerraduras por p\u00e9rdida de llaves. A la hora de contratar la p\u00f3liza que m\u00e1s se ajuste a tus necesidades, desde <\/span><a href=\"https:\/\/www.kelisto.es\/?utm_source=google&amp;utm_medium=contenidos&amp;utm_campaign=fotocasa\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Kelisto<\/b><\/a><span style=\"font-weight: 400;\"> te recomiendan que revises las diferentes coberturas que pueden incluir las compa\u00f1\u00edas. Las m\u00e1s habituales son las que se citan a continuaci\u00f3n:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27997\" src=\"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/wp-content\/uploads\/2018\/03\/seguro-alquiler-01.jpg\" alt=\"- - - -\" width=\"980\" height=\"654\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/03\/seguro-alquiler-01.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/03\/seguro-alquiler-01-300x200.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/03\/seguro-alquiler-01-150x100.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/03\/seguro-alquiler-01-768x513.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<h2>1. Atraco fuera de la vivienda<\/h2>\n<p><span style=\"font-weight: 400;\">Por lo general,\u00a0<\/span><b>la cobertura de atraco fuera de la vivienda solo es efectiva cuando el robo se ha producido con intimidaci\u00f3n<\/b><span style=\"font-weight: 400;\">, es decir, la compa\u00f1\u00eda no cubrir\u00e1 el coste de los bienes sustra\u00eddos si ha sido consecuencia de un descuido, lo que se conoce como hurto. Adem\u00e1s, para que recibas la indemnizaci\u00f3n, los objetos deben estar previamente declarados en tu p\u00f3liza de seguro de hogar como parte del contenido.<\/span><\/p>\n<p><b>Antes de contratar un seguro de hogar es importante conocer cu\u00e1l es el alcance de esta cobertura<\/b><span style=\"font-weight: 400;\">, ya que los l\u00edmites que se garantizan ante este tipo de situaciones var\u00edan seg\u00fan las condiciones particulares de cada p\u00f3liza.\u00a0 <\/span><\/p>\n<h2>2. Reposici\u00f3n de documentos<\/h2>\n<p><span style=\"font-weight: 400;\">Cuando sufres el robo de una cartera o de un bolso es muy posible que tambi\u00e9n pierdas documentos personales como, por ejemplo, el DNI, el carn\u00e9 de conducir u otros t\u00edtulos acreditativos cuya renovaci\u00f3n, en algunos casos, conlleva un coste. As\u00ed, algunas compa\u00f1\u00edas <\/span><b>garantizan hasta el 100% de los gastos derivados de la expedici\u00f3n de copias o duplicados de documentos p\u00fablicos personales en caso de robo o hurto<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con respecto a otro tipo de documentos particulares \u2013 escrituras de la casa, contratos de arrendamiento, etc. \u2013, es recomendable que verifiques lo que se\u00f1ala sobre ello tu\u00a0<\/span><b>seguro de hogar<\/b><span style=\"font-weight: 400;\">. Por ejemplo, hay aseguradoras que solo cubren su reposici\u00f3n en el caso de que el deterioro se produzca dentro de la vivienda.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">3. Uso fraudulento de tarjetas de cr\u00e9dito<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Con esta prestaci\u00f3n tendr\u00e1s <\/span><b>cubiertas las p\u00e9rdidas econ\u00f3micas<\/b><span style=\"font-weight: 400;\"> que se deriven del uso fraudulento por terceros de cheques y tarjetas de d\u00e9bito o de cr\u00e9dito, siempre y cuando est\u00e9n a tu nombre o al de cualquier persona contemplada previamente en la p\u00f3liza. \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este caso tambi\u00e9n se establecen ciertas condiciones:\u00a0<\/span><b>la garant\u00eda se extiende hasta las 48 horas posteriores al robo de la tarjeta<\/b><span style=\"font-weight: 400;\">, ya que se entiende que el afectado habr\u00e1 tenido tiempo para anular la tarjeta con el fin de que se produzcan p\u00e9rdidas mayores. Adem\u00e1s, se deber\u00e1 denunciar el hecho a las autoridades policiales y no se reintegrar\u00e1n aquellos importes que ya est\u00e9n cubiertos por la entidad bancaria o por la emisora de las tarjetas o cheques. Igual que en el caso del robo,\u00a0<\/span><b>el l\u00edmite de dinero a devolver se define en el contrato suscrito con la compa\u00f1\u00eda<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2>4. Robos y da\u00f1os durante desplazamientos<\/h2>\n<p><span style=\"font-weight: 400;\">\u00bfHas perdido el equipaje al viajar en avi\u00f3n o se han da\u00f1ado algunos objetos que iban dentro de la maleta? Aunque este tipo de situaciones se pueden reclamar a la aerol\u00ednea,\u00a0<\/span><b>muchas aseguradoras tambi\u00e9n cubren el da\u00f1o y el robo de equipajes no solo en aviones, sino siempre que se viaje en transporte p\u00fablico<\/b><span style=\"font-weight: 400;\">\u00a0o, incluso, si hay un robo en el interior del maletero de un veh\u00edculo particular.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, <\/span><b>esta cobertura s\u00f3lo se aplica en caso de traslados por vacaciones<\/b><span style=\"font-weight: 400;\">. Es decir, se excluyen viajes por motivos laborales o que supongan estancias fuera de la vivienda habitual superiores a tres meses.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-30755\" src=\"https:\/\/blog-fotocasa-admin.wpsites-scmspain.com\/blog\/wp-content\/uploads\/2018\/07\/seguro-humedades.jpg\" alt=\"\u00daltimo piso y humedades en el techo, \u00bfa qui\u00e9n reclamar?\" width=\"980\" height=\"550\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/07\/seguro-humedades.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/07\/seguro-humedades-300x168.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/07\/seguro-humedades-150x84.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/07\/seguro-humedades-768x431.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<h2>5. Objetos en el hotel o en la vivienda vacacional<\/h2>\n<p><span style=\"font-weight: 400;\">Si has alquilado un apartamento para tus vacaciones o te alojas en un hotel, debes saber que varias compa\u00f1\u00edas de seguros cubren los da\u00f1os materiales, p\u00e9rdidas o robos en los bienes asegurados, pr\u00e1cticamente en las mismas condiciones que si el imprevisto se produjera en tu domicilio habitual.<\/span><\/p>\n<p><b>Se establecen tambi\u00e9n ciertas limitaciones en estas coberturas<\/b><span style=\"font-weight: 400;\"> como, por ejemplo, que solo se garantiza hasta el 10% del capital contratado para el contenido o que se excluya el dinero en efectivo u objetos de valor que no est\u00e9n guardados en caja fuerte.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">6. Olvido de llaves<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La reposici\u00f3n de la cerradura en caso de p\u00e9rdida de llaves es una cobertura que incluyen la mayor\u00eda de las aseguradoras, aunque\u00a0<\/span><b>no es normal que se contemple en los seguros m\u00e1s b\u00e1sicos<\/b><span style=\"font-weight: 400;\">. Algunas compa\u00f1\u00edas no establecen l\u00edmites al respecto, pero otras s\u00ed lo hacen y marcan un gasto m\u00e1ximo de 500 euros.<\/span><\/p>\n<h2>7. Responsabilidad Civil<\/h2>\n<p><span style=\"font-weight: 400;\">Este tipo de cobertura se incluye en todos los\u00a0<\/span><b>seguros de hogar<\/b><span style=\"font-weight: 400;\">\u00a0pero, a pesar de ello, a veces\u00a0<\/span><b>desconocemos su alcance<\/b><span style=\"font-weight: 400;\">. En l\u00edneas generales, <\/span><b>te protege ante los da\u00f1os que puedas ocasionar a terceros <\/b><span style=\"font-weight: 400;\">en el \u00e1mbito de la vida privada \u2013 por ejemplo, cuando un escape de agua en tu hogar produce desperfectos en la vivienda de un vecino \u2013, pero tambi\u00e9n ante ciertos acontecimientos causados fuera del domicilio habitual. Entre otros riesgos, cubre aquellos derivados de la pr\u00e1ctica deportiva o de la estancia en campings, por ejemplo.<\/span><\/p>\n<h2>8. Mascotas<\/h2>\n<p><b>Si tu mascota no est\u00e1 considerada como animal peligroso, cualquier imprevisto que pueda causar est\u00e1 cubierto en tu seguro<\/b><span style=\"font-weight: 400;\">\u00a0(siempre que la compa\u00f1\u00eda incluya esta garant\u00eda), con lo que no necesitar\u00e1s contratar un seguro espec\u00edfico para ello.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSab\u00edas que hay una serie de coberturas del seguro de hogar que pueden protegerte aunque no est\u00e9s en casa? Te las detallamos a continuaci\u00f3n.<\/p>\n","protected":false},"author":86,"featured_media":32163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"categories":[2285],"tags":[2716,409,907,2411,2713,408],"class_list":["post-39644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar","tag-coberturas-seguros","tag-contratar-seguros","tag-dudas-seguros","tag-seguro","tag-seguro-del-hogar","tag-seguros-del-hogar"],"modified_by":"fotocasa","_links":{"self":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/39644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/comments?post=39644"}],"version-history":[{"count":0,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/39644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media\/32163"}],"wp:attachment":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media?parent=39644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/categories?post=39644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/tags?post=39644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}