{"id":34102,"date":"2018-12-29T09:00:32","date_gmt":"2018-12-29T08:00:32","guid":{"rendered":"https:\/\/www.fotocasa.es\/fotocasa-life\/?p=34102"},"modified":"2020-11-27T13:25:50","modified_gmt":"2020-11-27T12:25:50","slug":"impugnar-acuerdos-comunidad","status":"publish","type":"post","link":"https:\/\/www.fotocasa.es\/fotocasa-life\/hogar\/impugnar-acuerdos-comunidad\/","title":{"rendered":"\u00bfSe pueden impugnar los acuerdos de la comunidad?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Durante una Junta de Propietarios no siempre se llega a decisiones con las que todo el mundo est\u00e1 de acuerdo. <\/span><b>\u00bfQu\u00e9 pasa si, tras una Junta de Propietarios, alguien no queda contento con la decisi\u00f3n tomada? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Es interesante conocer que los <\/span><b>acuerdos<\/b><span style=\"font-weight: 400;\"> tomados en la junta <\/span><b>pueden ser impugnados<\/b><span style=\"font-weight: 400;\">, es decir, se puede solicitar al Juzgado que quede sin efecto alguna decisi\u00f3n que se haya tomado en dicha Junta, pero solo cumpliendo determinados requisitos establecidos en el art\u00edculo 18 de la Ley de Propiedad Horizontal. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Solo pueden impugnar los acuerdos, los <\/span><b>propietarios<\/b><span style=\"font-weight: 400;\"> que hubiesen salvado su voto en junta, los ausentes y los que indebidamente hubiesen sido privados del derecho de voto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Debemos tener cuidado, porque, en el caso de que, pese a haber sido citados debidamente, no hayamos asistido a la reuni\u00f3n de la Junta de Propietarios, solo tendremos <strong>treinta d\u00edas desde que tengamos conocimiento del acuerdo<\/strong> o recibamos el acta, para manifestar que no estamos de acuerdo por cualquier medio que deje constancia. En caso contrario, si no decimos nada, ello significar\u00eda un voto afirmativo, con lo que ya no podr\u00edamos impugnar. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otra parte, hay que tener en cuenta que para poder impugnar acuerdos <\/span><b>se requiere estar al corriente de los pagos <\/b><span style=\"font-weight: 400;\">de las deudas vencidas con la Comunidad o proceder previamente a su consignaci\u00f3n judicial. Esta regla no se aplicar\u00e1 para la impugnaci\u00f3n de acuerdos de la junta relativos al establecimiento o alteraci\u00f3n de las cuotas de participaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, los acuerdos de la Junta de propietarios ser\u00e1n impugnables ante los Tribunales solo <\/span><b>en los siguientes supuestos y dentro de los siguientes plazos<\/b><span style=\"font-weight: 400;\">: <\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cuando sean contrarios a la ley o a los Estatutos de la<\/span> <span style=\"font-weight: 400;\">Comunidad de propietarios, durante 1 a\u00f1o.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cuando resulten gravemente lesivos para los intereses de la propia Comunidad en beneficio de uno o varios propietarios, durante 3 meses.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cuando supongan un grave perjuicio para alg\u00fan propietario que no tenga obligaci\u00f3n jur\u00eddica de soportarlo o se haya adoptado con abuso de derecho, durante 3 meses.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-31611\" src=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/09\/ocupacion-ilegal.jpg\" alt=\"La ocupaci\u00f3n ilegal: un frenazo al sector inmobiliario\" width=\"980\" height=\"550\" title=\"-\" srcset=\"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/09\/ocupacion-ilegal.jpg 980w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/09\/ocupacion-ilegal-300x168.jpg 300w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/09\/ocupacion-ilegal-150x84.jpg 150w, https:\/\/www.fotocasa.es\/fotocasa-life\/wp-content\/uploads\/2018\/09\/ocupacion-ilegal-768x431.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Es importante tener en cuenta, que los plazos indicados para impugnar los acuerdos de la Junta de Propietarios <\/span><b>son plazos de caducidad<\/b><span style=\"font-weight: 400;\">, lo cual significa que no se pueden interrumpir, como sucede con los plazos de prescripci\u00f3n. Es decir, que si se dan los requisitos indicados la demanda tendr\u00eda que estar interpuesta necesariamente dentro de dichos plazos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, hay que tener en cuenta que <\/span><b>los acuerdos son ejecutivos<\/b><span style=\"font-weight: 400;\">, es decir que la impugnaci\u00f3n de los mismos no suspender\u00e1 su ejecuci\u00f3n, salvo que el juez as\u00ed lo disponga con car\u00e1cter cautelar, a solicitud del demandante, o\u00edda la comunidad de propietarios. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si te han quedado dudas sobre <\/span><b>c\u00f3mo impugnar los acuerdos de tu comunidad <\/b><span style=\"font-weight: 400;\">o cualquier otra pregunta sobre temas como vecinos, comunidades, compra o venta de una vivienda, los abogados expertos de Leg\u00e1litas te ofrecen, por ser lector de Fotocasa una\u00a0<\/span><a href=\"https:\/\/www.legalitas.com\/promo\/fotocasa\/consulta-gratuita-vivienda\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">consulta online GRATIS<\/span><\/a> <span style=\"font-weight: 400;\">aqu\u00ed\u00a0o llamando al tel\u00e9fono\u00a0<\/span><b>91 558 97 64<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante una Junta de Propietarios no siempre se llega a decisiones con las que todo el mundo est\u00e1 de acuerdo. \u00bfQu\u00e9 pasa si alguien no queda contento?<\/p>\n","protected":false},"author":38,"featured_media":34104,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"categories":[2285],"tags":[2008,1389,73,169,219],"class_list":["post-34102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar","tag-comunidad-de-propietarios","tag-comunidades-de-propietarios","tag-comunidades-de-vecinos","tag-legal","tag-problemas-comunidades-vecinos"],"modified_by":"fotocasa","_links":{"self":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/34102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/comments?post=34102"}],"version-history":[{"count":0,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/posts\/34102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media\/34104"}],"wp:attachment":[{"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/media?parent=34102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/categories?post=34102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotocasa.es\/fotocasa-life\/wp-json\/wp\/v2\/tags?post=34102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}